{"id":8628,"date":"2025-09-30T08:11:09","date_gmt":"2025-09-30T06:11:09","guid":{"rendered":"https:\/\/www.portopetro-living.es\/?p=8628"},"modified":"2025-10-01T14:44:54","modified_gmt":"2025-10-01T12:44:54","slug":"ref-pro157-high-quality-townhouse-with-modern-architecture-in-felanitx","status":"publish","type":"post","link":"https:\/\/www.portopetro-living.es\/en\/ref-pro157-high-quality-townhouse-with-modern-architecture-in-felanitx\/","title":{"rendered":"Ref. PRO157 &#8211; High-quality townhouse with modern architecture in Felanitx"},"content":{"rendered":"<div class=\"pgc-sgb-cb wp-block-pgcsimplygalleryblock-slider \" data-gallery-id=\"52f43673\"style=&quot;min-height:400px&quot;><div class=\"sgb-preloader\" id=\"pr_52f43673\">\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div>\n\t<div class=\"sgb-square\" style=\"background:#d4d4d4\"><\/div><\/div><div class=\"simply-gallery-amp pgc_sgb_slider \"><noscript><div class=\"sgb-gallery\"><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/01_gartenansicht\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/01_Gartenansicht-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/01_Gartenansicht-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/01_Gartenansicht-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/01_Gartenansicht.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/02_garten-2\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/02_Garten-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/02_Garten-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/02_Garten-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/02_Garten.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/03_eingang\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/03_Eingang-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/03_Eingang-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/03_Eingang-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/03_Eingang.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/04_aufang\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/04_Aufang-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/04_Aufang-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/04_Aufang-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/04_Aufang.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/05_wohnen-1\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/05_Wohnen-1-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/05_Wohnen-1-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/05_Wohnen-1-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/05_Wohnen-1.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/06_wohnen-2\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/06_Wohnen-2-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/06_Wohnen-2-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/06_Wohnen-2-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/06_Wohnen-2.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/07_essen\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/07_Essen-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/07_Essen-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/07_Essen-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/07_Essen.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/08_kueche-3\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/08_Kueche-1-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/08_Kueche-1-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/08_Kueche-1-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/08_Kueche-1.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/09_gaeste\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/09_Gaeste-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/09_Gaeste-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/09_Gaeste-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/09_Gaeste.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/10_gaestebad\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/10_Gaestebad-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/10_Gaestebad-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/10_Gaestebad-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/10_Gaestebad.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/11_galerie-kamin\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/11_Galerie-Kamin-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/11_Galerie-Kamin-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/11_Galerie-Kamin-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/11_Galerie-Kamin.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/12_schlafen-2-2\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/12_Schlafen-2-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/12_Schlafen-2-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/12_Schlafen-2-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/12_Schlafen-2.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/13_bad-en-suite-2\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/13_Bad-en-Suite-2-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/13_Bad-en-Suite-2-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/13_Bad-en-Suite-2-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/13_Bad-en-Suite-2.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/14_schlafen-2-3\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/14_Schlafen-2-1-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/14_Schlafen-2-1-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/14_Schlafen-2-1-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/14_Schlafen-2-1.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/15_schlafen-1\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/15_Schlafen-1-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/15_Schlafen-1-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/15_Schlafen-1-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/15_Schlafen-1.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/16_bad-en-suite-1\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/16_Bad-en-Suite-1-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/16_Bad-en-Suite-1-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/16_Bad-en-Suite-1-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/16_Bad-en-Suite-1.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/17_bad-en-suite-1\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/17_Bad-en-Suite-1-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/17_Bad-en-Suite-1-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/17_Bad-en-Suite-1-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/17_Bad-en-Suite-1.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><div class=\"sgb-item\"><a href=\"https:\/\/www.portopetro-living.es\/18_ankleide\/\" target=\"_blank\"><img decoding=\"async\" alt=\"\" width=\"300\" height=\"225\" loading=\"lazy\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/18_Ankleide-300x225.jpg\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/18_Ankleide-300x225.jpg 300w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/18_Ankleide-1024x768.jpg 1024w,https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/18_Ankleide.jpg 1280w\" sizes=\"auto, 250px\"\/><\/a><\/div><\/div><\/noscript><\/div><script type=\"application\/json\" class=\"sgb-data\">{\"sliderAdminWidth\":819,\"collectionColumns\":2,\"galleryType\":\"pgc_sgb_slider\",\"galleryId\":\"52f43673\",\"images\":[{\"id\":8610,\"title\":\"01_Gartenansicht\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/01_Gartenansicht.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/01_gartenansicht\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/01_Gartenansicht-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/01_Gartenansicht-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/01_Gartenansicht-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/01_Gartenansicht.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593351634\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"20\",\"shutter_speed\":\"0.00037593984962406\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/01_gartenansicht\/\"},{\"id\":8611,\"title\":\"02_Garten\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/02_Garten.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/02_garten-2\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/02_Garten-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/02_Garten-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/02_Garten-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/02_Garten.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593351458\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"20\",\"shutter_speed\":\"0.00044903457566233\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/02_garten-2\/\"},{\"id\":8612,\"title\":\"03_Eingang\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/03_Eingang.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/03_eingang\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/03_Eingang-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/03_Eingang-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/03_Eingang-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/03_Eingang.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593352273\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"40\",\"shutter_speed\":\"0.01\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/03_eingang\/\"},{\"id\":8613,\"title\":\"04_Aufang\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/04_Aufang.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/04_aufang\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/04_Aufang-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/04_Aufang-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/04_Aufang-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/04_Aufang.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593352488\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"40\",\"shutter_speed\":\"0.058823529411765\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/04_aufang\/\"},{\"id\":8614,\"title\":\"05_Wohnen 1\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/05_Wohnen-1.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/05_wohnen-1\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/05_Wohnen-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/05_Wohnen-1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/05_Wohnen-1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/05_Wohnen-1.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593352788\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"40\",\"shutter_speed\":\"0.03030303030303\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/05_wohnen-1\/\"},{\"id\":8615,\"title\":\"06_Wohnen 2\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/06_Wohnen-2.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/06_wohnen-2\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/06_Wohnen-2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/06_Wohnen-2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/06_Wohnen-2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/06_Wohnen-2.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593352676\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"32\",\"shutter_speed\":\"0.02\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/06_wohnen-2\/\"},{\"id\":8616,\"title\":\"07_Essen\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/07_Essen.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/07_essen\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/07_Essen-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/07_Essen-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/07_Essen-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/07_Essen.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593352745\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"25\",\"shutter_speed\":\"0.01\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/07_essen\/\"},{\"id\":8617,\"title\":\"08_Kueche\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/08_Kueche-1.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/08_kueche-3\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/08_Kueche-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/08_Kueche-1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/08_Kueche-1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/08_Kueche-1.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593353108\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"25\",\"shutter_speed\":\"0.03030303030303\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/08_kueche-3\/\"},{\"id\":8618,\"title\":\"09_Gaeste\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/09_Gaeste.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/09_gaeste\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/09_Gaeste-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/09_Gaeste-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/09_Gaeste-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/09_Gaeste.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593352391\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"50\",\"shutter_speed\":\"0.058823529411765\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/09_gaeste\/\"},{\"id\":8619,\"title\":\"10_Gaestebad\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/10_Gaestebad.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/10_gaestebad\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/10_Gaestebad-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/10_Gaestebad-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/10_Gaestebad-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/10_Gaestebad.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593352876\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"32\",\"shutter_speed\":\"0.03030303030303\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/10_gaestebad\/\"},{\"id\":8620,\"title\":\"11_Galerie Kamin\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/11_Galerie-Kamin.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/11_galerie-kamin\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/11_Galerie-Kamin-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/11_Galerie-Kamin-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/11_Galerie-Kamin-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/11_Galerie-Kamin.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593353197\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"32\",\"shutter_speed\":\"0.03030303030303\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/11_galerie-kamin\/\"},{\"id\":8621,\"title\":\"12_Schlafen 2\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/12_Schlafen-2.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/12_schlafen-2-2\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/12_Schlafen-2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/12_Schlafen-2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/12_Schlafen-2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/12_Schlafen-2.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593353663\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"20\",\"shutter_speed\":\"0.008\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/12_schlafen-2-2\/\"},{\"id\":8622,\"title\":\"13_Bad en Suite 2\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/13_Bad-en-Suite-2.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/13_bad-en-suite-2\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/13_Bad-en-Suite-2-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/13_Bad-en-Suite-2-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/13_Bad-en-Suite-2-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/13_Bad-en-Suite-2.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593353806\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"20\",\"shutter_speed\":\"0.0085470085470085\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/13_bad-en-suite-2\/\"},{\"id\":8623,\"title\":\"14_Schlafen 2\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/14_Schlafen-2-1.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/14_schlafen-2-3\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/14_Schlafen-2-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/14_Schlafen-2-1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/14_Schlafen-2-1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/14_Schlafen-2-1.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593353638\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"20\",\"shutter_speed\":\"0.0025252525252525\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/14_schlafen-2-3\/\"},{\"id\":8624,\"title\":\"15_Schlafen 1\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/15_Schlafen-1.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/15_schlafen-1\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/15_Schlafen-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/15_Schlafen-1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/15_Schlafen-1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/15_Schlafen-1.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593354684\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"25\",\"shutter_speed\":\"0.01\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/15_schlafen-1\/\"},{\"id\":8625,\"title\":\"16_Bad en Suite 1\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/16_Bad-en-Suite-1.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/16_bad-en-suite-1\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/16_Bad-en-Suite-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/16_Bad-en-Suite-1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/16_Bad-en-Suite-1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/16_Bad-en-Suite-1.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593354253\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"32\",\"shutter_speed\":\"0.01\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/16_bad-en-suite-1\/\"},{\"id\":8626,\"title\":\"17_Bad en Suite 1\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/17_Bad-en-Suite-1.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/17_bad-en-suite-1\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/17_Bad-en-Suite-1-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/17_Bad-en-Suite-1-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/17_Bad-en-Suite-1-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/17_Bad-en-Suite-1.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593354206\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"20\",\"shutter_speed\":\"0.0064516129032258\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/17_bad-en-suite-1\/\"},{\"id\":8627,\"title\":\"18_Ankleide\",\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/18_Ankleide.jpg\",\"link\":\"https:\/\/www.portopetro-living.es\/18_ankleide\/\",\"alt\":\"\",\"description\":\"\",\"caption\":\"\",\"mime\":\"image\/jpeg\",\"type\":\"image\",\"width\":1280,\"height\":960,\"sizes\":{\"thumbnail\":{\"height\":150,\"width\":150,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/18_Ankleide-150x150.jpg\",\"orientation\":\"landscape\"},\"medium\":{\"height\":225,\"width\":300,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/18_Ankleide-300x225.jpg\",\"orientation\":\"landscape\"},\"large\":{\"height\":768,\"width\":1024,\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/18_Ankleide-1024x768.jpg\",\"orientation\":\"landscape\"},\"full\":{\"url\":\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2025\/09\/18_Ankleide.jpg\",\"height\":960,\"width\":1280,\"orientation\":\"landscape\"}},\"imageMeta\":{\"aperture\":\"1.8\",\"credit\":\"\",\"camera\":\"iPhone 7\",\"caption\":\"\",\"created_timestamp\":\"1593354752\",\"copyright\":\"\",\"focal_length\":\"3.99\",\"iso\":\"25\",\"shutter_speed\":\"0.03030303030303\",\"title\":\"\",\"orientation\":\"1\",\"keywords\":[]},\"meta\":false,\"postlink\":\"https:\/\/www.portopetro-living.es\/18_ankleide\/\"}],\"orderBy\":\"id\",\"itemsMetaDataCollection\":[]}<\/script><script>(function(){if(window.PGC_SGB && window.PGC_SGB.searcher){window.PGC_SGB.searcher.initBlocks()}})()<\/script><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center has-text-color\" style=\"color:#868686\">High-quality townhouse with modern architecture in Felanitx<\/h4>\n\n\n\n<p class=\"has-text-align-center\">This townhouse combines authentic living in a central location in Felanitx with a high level of comfort. Renovated to a modern standard in 2006 \u2013 2008, it has nevertheless retained its charm through traditional elements such as the solid wood entrance door and the use of high-quality Santany\u00ed stone. The house extends over two floors. On the ground floor, you are welcomed by an entrance hall with windbreak, a spacious open-plan living and dining area, a kitchen with adjoining utility room, as well as a bedroom and a guest bathroom. Upstairs, a modern gallery with high ceilings, a sophisticated lighting concept and a fireplace awaits you, along with two further generous bedrooms, each with en-suite bathrooms, and a dressing room. The property offers a modern mediterranean-style garden with an irrigation system, a large terrace and access to the sunny rooftop terrace with panoramic views. A technical\/storage room and a garage complete the layout.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background is-style-default\" style=\"background-color:#6db3e3;color:#6db3e3\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1251\" height=\"1108\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Grundstueck.png\" alt=\"Grundst\u00fcck\" class=\"wp-image-1336\" style=\"width:70px\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Grundstueck.png 1251w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Grundstueck-300x266.png 300w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Grundstueck-1024x907.png 1024w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Grundstueck-768x680.png 768w\" sizes=\"auto, (max-width: 1251px) 100vw, 1251px\" \/><figcaption class=\"wp-element-caption\"><strong>215 m\u00b2<\/strong><\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1250\" height=\"1008\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Flaeche-Haus.png\" alt=\"Wohnfl\u00e4che\" class=\"wp-image-1335\" style=\"width:70px\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Flaeche-Haus.png 1250w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Flaeche-Haus-300x242.png 300w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Flaeche-Haus-1024x826.png 1024w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Flaeche-Haus-768x619.png 768w\" sizes=\"auto, (max-width: 1250px) 100vw, 1250px\" \/><figcaption class=\"wp-element-caption\"><strong>214 m\u00b2<\/strong><\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1246\" height=\"779\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Schlafzimmer.png\" alt=\"Schlafzimmer\" class=\"wp-image-1338\" style=\"width:70px\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Schlafzimmer.png 1246w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Schlafzimmer-300x188.png 300w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Schlafzimmer-1024x640.png 1024w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Schlafzimmer-768x480.png 768w\" sizes=\"auto, (max-width: 1246px) 100vw, 1246px\" \/><figcaption class=\"wp-element-caption\"><strong>3<\/strong><\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1267\" height=\"1244\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Badezimmer.png\" alt=\"Badezimmer\" class=\"wp-image-1334\" style=\"width:70px;height:68px\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Badezimmer.png 1267w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Badezimmer-300x295.png 300w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Badezimmer-1024x1005.png 1024w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Badezimmer-768x754.png 768w\" sizes=\"auto, (max-width: 1267px) 100vw, 1267px\" \/><figcaption class=\"wp-element-caption\"><strong>3<\/strong><\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1249\" height=\"1160\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Pool-Icon.png\" alt=\"Pool\" class=\"wp-image-1333\" style=\"width:70px\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Pool-Icon.png 1249w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Pool-Icon-300x279.png 300w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Pool-Icon-1024x951.png 1024w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Pool-Icon-768x713.png 768w\" sizes=\"auto, (max-width: 1249px) 100vw, 1249px\" \/><figcaption class=\"wp-element-caption\"><strong>No<\/strong><\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1325\" height=\"1278\" src=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Preis.png\" alt=\"Preis\" class=\"wp-image-1337\" style=\"width:80px\" srcset=\"https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Preis.png 1325w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Preis-300x289.png 300w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Preis-1024x988.png 1024w, https:\/\/www.portopetro-living.es\/wp-content\/uploads\/2023\/01\/Preis-768x741.png 768w\" sizes=\"auto, (max-width: 1325px) 100vw, 1325px\" \/><figcaption class=\"wp-element-caption\"><strong>&#8211;<\/strong><\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-alpha-channel-opacity has-background\" style=\"background-color:#6db3e3;color:#6db3e3\"\/>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50 is-style-default\"><a class=\"wp-block-button__link has-nv-site-bg-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.portopetro-living.es\/en\/kontakt\/\" style=\"border-radius:9px;background-color:#6db3e3\" target=\"_blank\" rel=\"noreferrer noopener\">REQUEST SPECIFICATION<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-nv-text-dark-bg-color has-alpha-channel-opacity has-nv-text-dark-bg-background-color has-background is-style-default\"\/>\n","protected":false},"excerpt":{"rendered":"<p>High-quality townhouse with modern architecture in Felanitx This townhouse combines authentic living in a central location in Felanitx with a high level of comfort. Renovated to a modern standard in 2006 \u2013 2008, it has nevertheless retained its charm through traditional elements such as the solid wood entrance door and the use of high-quality Santany\u00ed&hellip;&nbsp;<a href=\"https:\/\/www.portopetro-living.es\/en\/ref-pro157-high-quality-townhouse-with-modern-architecture-in-felanitx\/\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Ref. PRO157 &#8211; High-quality townhouse with modern architecture in Felanitx<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":8670,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[26],"tags":[],"class_list":["post-8628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-immobilien"],"_links":{"self":[{"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/posts\/8628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/comments?post=8628"}],"version-history":[{"count":3,"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/posts\/8628\/revisions"}],"predecessor-version":[{"id":8634,"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/posts\/8628\/revisions\/8634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/media\/8670"}],"wp:attachment":[{"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/media?parent=8628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/categories?post=8628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portopetro-living.es\/en\/wp-json\/wp\/v2\/tags?post=8628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}